{"id":33343,"date":"2024-08-16T08:39:27","date_gmt":"2024-08-16T06:39:27","guid":{"rendered":"https:\/\/deltabirdingfestival.com\/activity\/flyways-the-untold-journey-of-migratory-shorebirds\/"},"modified":"2024-08-16T08:47:04","modified_gmt":"2024-08-16T06:47:04","slug":"flyways-the-untold-journey-of-migratory-shorebirds","status":"publish","type":"activity","link":"https:\/\/deltabirdingfestival.com\/es\/actividades\/flyways-the-untold-journey-of-migratory-shorebirds\/","title":{"rendered":"FLYWAYS: The untold journey of migratory shorebirds"},"content":{"rendered":"<p><strong>Un viaje a vista de p\u00e1jaro en el mundo de las aves lim\u00edcolas migratorias. Los mejores atletas de resistencia del mundo vuelan hasta 9 d\u00edas sin cesar y necesitan tu ayuda.<\/strong><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\">Las aves lim\u00edcolas son los mejores atletas de resistencia del mundo. Migran sin parar durante hasta 9 d\u00edas sin comida ni agua: la migraci\u00f3n m\u00e1s larga conocida de cualquier especie. Vuelan miles de kil\u00f3metros a lo largo de antiguas rutas migratorias, viajan desde sus zonas de alimentaci\u00f3n en el hemisferio sur hasta el Alto \u00c1rtico y viceversa. Pero en solo 30 a\u00f1os, las poblaciones han disminuido precipitadamente. Las rutas migratorias que alguna vez rebosaban de vida est\u00e1n quedando inactivas. Se ha convertido en una carrera contra el tiempo para salvarlas.<\/p>\r\n<p>En Am\u00e9rica, Australia, Europa y Asia, los cient\u00edficos est\u00e1n abordando el desaf\u00edo de la conservaci\u00f3n de las aves playeras. Para los animales que trascienden fronteras, no es una tarea f\u00e1cil determinar por qu\u00e9 disminuyen. Usando la ciencia m\u00e1s reciente, incluida la tecnolog\u00eda de seguimiento revolucionaria en la Estaci\u00f3n Espacial Internacional, esperan descifrar sus misteriosas rutas migratorias y salvarlas. Una pel\u00edcula cautivadora sobre c\u00f3mo las aves lim\u00edcolas, a trav\u00e9s de sus incre\u00edbles migraciones a trav\u00e9s de los hemisferios, est\u00e1n sacando lo mejor de la humanidad y la ciencia para ayudar a salvarlas de declives precipitados.<\/p>\r\n<p>Este documental, dirigido por Randall Wood, surgi\u00f3 de la lectura del art\u00edculo de Jan Van Gils, con el que se puso en contacto. De hecho, Jan, este DBF24 dar\u00e1 una conferencia en la carpa 1 el s\u00e1bado sobre el calentamiento en el \u00e1rtico y c\u00f3mo lo siente el correlimos gordo durante su viaje de migraci\u00f3n. El director decidi\u00f3 que la historia del correlimos gordo ser\u00eda una de las que documentar\u00eda en la pel\u00edcula. De esta forma, el equipo del Randall se uni\u00f3 a la expedici\u00f3n cient\u00edfica de Jan en Mauritania en los a\u00f1os 2021 y 2022 y durante su viaje a Alaska donde se grabaron gran parte de las escenas.<\/p>\r\n<hr \/>\r\n<img loading=\"lazy\" decoding=\"async\" class=\"wp-image-33334\" src=\"https:\/\/deltabirdingfestival.com\/wp-content\/uploads\/2024\/08\/flyways-activitat-1080x720.webp\" alt=\"flyways activitat\" width=\"500\" height=\"333\" \/>","protected":false},"featured_media":33340,"template":"","meta":{"inline_featured_image":false,"footnotes":""},"any":[],"daysactivities":[],"locationactivities":[],"typesactivities":[],"class_list":["post-33343","activity","type-activity","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/deltabirdingfestival.com\/es\/wp-json\/wp\/v2\/activitats\/33343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/deltabirdingfestival.com\/es\/wp-json\/wp\/v2\/activitats"}],"about":[{"href":"https:\/\/deltabirdingfestival.com\/es\/wp-json\/wp\/v2\/types\/activity"}],"version-history":[{"count":0,"href":"https:\/\/deltabirdingfestival.com\/es\/wp-json\/wp\/v2\/activitats\/33343\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/deltabirdingfestival.com\/es\/wp-json\/wp\/v2\/media\/33340"}],"wp:attachment":[{"href":"https:\/\/deltabirdingfestival.com\/es\/wp-json\/wp\/v2\/media?parent=33343"}],"wp:term":[{"taxonomy":"any","embeddable":true,"href":"https:\/\/deltabirdingfestival.com\/es\/wp-json\/wp\/v2\/any?post=33343"},{"taxonomy":"daysactivities","embeddable":true,"href":"https:\/\/deltabirdingfestival.com\/es\/wp-json\/wp\/v2\/daysactivities?post=33343"},{"taxonomy":"locationactivities","embeddable":true,"href":"https:\/\/deltabirdingfestival.com\/es\/wp-json\/wp\/v2\/locationactivities?post=33343"},{"taxonomy":"typesactivities","embeddable":true,"href":"https:\/\/deltabirdingfestival.com\/es\/wp-json\/wp\/v2\/typesactivities?post=33343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}