{"id":40481,"date":"2026-04-10T14:09:34","date_gmt":"2026-04-10T12:09:34","guid":{"rendered":"https:\/\/deltabirdingfestival.com\/?p=40481"},"modified":"2026-04-10T14:17:19","modified_gmt":"2026-04-10T12:17:19","slug":"el-delta-photo-contest-regresa-renovado","status":"publish","type":"post","link":"https:\/\/deltabirdingfestival.com\/es\/el-delta-photo-contest-regresa-renovado\/","title":{"rendered":"\u00a1El Delta Photo Contest regresa renovado!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El Delta Photo Contest renueva su imagen y en esta novena edici\u00f3n busca redescubrir la mirada del fot\u00f3grafo estrenando dos nuevas categor\u00edas: conservaci\u00f3n y observaci\u00f3n. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La primera busca conocer la historia de un ave mediante la presentaci\u00f3n de tres im\u00e1genes; un relato visual que cuente desde la recuperaci\u00f3n de una especie amenazada hasta el seguimiento de un individuo dentro de un <em>local patch<\/em>. La segunda pretende dar una visi\u00f3n protagonista a la escasez, rareza, h\u00e1bitat, comportamiento u otras caracter\u00edsticas \u00fanicas de un ave, con el objetivo de celebrar la ornitolog\u00eda en cualquier parte del mundo. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De esta forma invitamos a participar a todo aquel amante de la naturaleza, tanto aficionado como profesional en el campo de la fotograf\u00eda y la ornitolog\u00eda, que comparta la idea de que las c\u00e1maras son una herramienta de conservaci\u00f3n y divulgaci\u00f3n muy \u00fatil para la protecci\u00f3n de las aves.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a1En abril se podr\u00e1n leer las bases y en mayo ya se podr\u00e1 entrar a participar!<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Delta Photo Contest renueva su imagen y en esta novena edici\u00f3n busca redescubrir la mirada del fot\u00f3grafo estrenando dos nuevas categor\u00edas: conservaci\u00f3n y observaci\u00f3n. La primera busca conocer la historia de un ave mediante la presentaci\u00f3n de tres im\u00e1genes; un relato visual que cuente desde la recuperaci\u00f3n de una especie amenazada hasta el seguimiento&#8230;<\/p>\n","protected":false},"author":10,"featured_media":40488,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[29],"tags":[],"class_list":["post-40481","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/deltabirdingfestival.com\/es\/wp-json\/wp\/v2\/posts\/40481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/deltabirdingfestival.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/deltabirdingfestival.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/deltabirdingfestival.com\/es\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/deltabirdingfestival.com\/es\/wp-json\/wp\/v2\/comments?post=40481"}],"version-history":[{"count":0,"href":"https:\/\/deltabirdingfestival.com\/es\/wp-json\/wp\/v2\/posts\/40481\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/deltabirdingfestival.com\/es\/wp-json\/wp\/v2\/media\/40488"}],"wp:attachment":[{"href":"https:\/\/deltabirdingfestival.com\/es\/wp-json\/wp\/v2\/media?parent=40481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/deltabirdingfestival.com\/es\/wp-json\/wp\/v2\/categories?post=40481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/deltabirdingfestival.com\/es\/wp-json\/wp\/v2\/tags?post=40481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}